{"id":3801,"date":"2024-01-16T14:48:23","date_gmt":"2024-01-16T13:48:23","guid":{"rendered":"https:\/\/maked.it\/portfolio\/empowerment-in-a-label\/"},"modified":"2024-03-19T13:29:10","modified_gmt":"2024-03-19T12:29:10","slug":"empowerment-in-a-label","status":"publish","type":"portfolio","link":"https:\/\/maked.it\/en\/portfolio\/empowerment-in-a-label\/","title":{"rendered":"Empowerment in a label"},"featured_media":3802,"template":"","meta":{"_acf_changed":false},"brand":[43],"homepage":[],"servizio":[19],"settore":[12],"class_list":["post-3801","portfolio","type-portfolio","status-publish","has-post-thumbnail","hentry","brand-saugella","servizio-packaging","settore-healthcare"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Empowerment in a label - Maked<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/maked.it\/en\/portfolio\/empowerment-in-a-label\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Empowerment in a label - Maked\" \/>\n<meta property=\"og:url\" content=\"https:\/\/maked.it\/en\/portfolio\/empowerment-in-a-label\/\" \/>\n<meta property=\"og:site_name\" content=\"Maked\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/makedagency\/\" \/>\n<meta property=\"article:modified_time\" content=\"2024-03-19T12:29:10+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/maked.it\/wp-content\/uploads\/2024\/01\/prj-en_saugella-00-cover-all-B.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2000\" \/>\n\t<meta property=\"og:image:height\" content=\"1125\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/maked.it\\\/en\\\/portfolio\\\/empowerment-in-a-label\\\/\",\"url\":\"https:\\\/\\\/maked.it\\\/en\\\/portfolio\\\/empowerment-in-a-label\\\/\",\"name\":\"Empowerment in a label - Maked\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/maked.it\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/maked.it\\\/en\\\/portfolio\\\/empowerment-in-a-label\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/maked.it\\\/en\\\/portfolio\\\/empowerment-in-a-label\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/maked.it\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/prj-en_saugella-00-cover-all-B.jpg\",\"datePublished\":\"2024-01-16T13:48:23+00:00\",\"dateModified\":\"2024-03-19T12:29:10+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/maked.it\\\/en\\\/portfolio\\\/empowerment-in-a-label\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/maked.it\\\/en\\\/portfolio\\\/empowerment-in-a-label\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/maked.it\\\/en\\\/portfolio\\\/empowerment-in-a-label\\\/#primaryimage\",\"url\":\"https:\\\/\\\/maked.it\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/prj-en_saugella-00-cover-all-B.jpg\",\"contentUrl\":\"https:\\\/\\\/maked.it\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/prj-en_saugella-00-cover-all-B.jpg\",\"width\":2000,\"height\":1125},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/maked.it\\\/en\\\/portfolio\\\/empowerment-in-a-label\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/maked.it\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Empowerment in a label\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/maked.it\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/maked.it\\\/en\\\/\",\"name\":\"Maked\",\"description\":\"We make design and digital communication\",\"publisher\":{\"@id\":\"https:\\\/\\\/maked.it\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/maked.it\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/maked.it\\\/en\\\/#organization\",\"name\":\"Graphic Store s.r.l.\",\"url\":\"https:\\\/\\\/maked.it\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/maked.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/maked.it\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/logo-maked.png\",\"contentUrl\":\"https:\\\/\\\/maked.it\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/logo-maked.png\",\"width\":340,\"height\":88,\"caption\":\"Graphic Store s.r.l.\"},\"image\":{\"@id\":\"https:\\\/\\\/maked.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/makedagency\\\/\",\"https:\\\/\\\/www.instagram.com\\\/makedagency\\\/\",\"https:\\\/\\\/it.linkedin.com\\\/company\\\/maked\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Empowerment in a label - Maked","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/maked.it\/en\/portfolio\/empowerment-in-a-label\/","og_locale":"en_US","og_type":"article","og_title":"Empowerment in a label - Maked","og_url":"https:\/\/maked.it\/en\/portfolio\/empowerment-in-a-label\/","og_site_name":"Maked","article_publisher":"https:\/\/www.facebook.com\/makedagency\/","article_modified_time":"2024-03-19T12:29:10+00:00","og_image":[{"width":2000,"height":1125,"url":"https:\/\/maked.it\/wp-content\/uploads\/2024\/01\/prj-en_saugella-00-cover-all-B.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/maked.it\/en\/portfolio\/empowerment-in-a-label\/","url":"https:\/\/maked.it\/en\/portfolio\/empowerment-in-a-label\/","name":"Empowerment in a label - Maked","isPartOf":{"@id":"https:\/\/maked.it\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/maked.it\/en\/portfolio\/empowerment-in-a-label\/#primaryimage"},"image":{"@id":"https:\/\/maked.it\/en\/portfolio\/empowerment-in-a-label\/#primaryimage"},"thumbnailUrl":"https:\/\/maked.it\/wp-content\/uploads\/2024\/01\/prj-en_saugella-00-cover-all-B.jpg","datePublished":"2024-01-16T13:48:23+00:00","dateModified":"2024-03-19T12:29:10+00:00","breadcrumb":{"@id":"https:\/\/maked.it\/en\/portfolio\/empowerment-in-a-label\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/maked.it\/en\/portfolio\/empowerment-in-a-label\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/maked.it\/en\/portfolio\/empowerment-in-a-label\/#primaryimage","url":"https:\/\/maked.it\/wp-content\/uploads\/2024\/01\/prj-en_saugella-00-cover-all-B.jpg","contentUrl":"https:\/\/maked.it\/wp-content\/uploads\/2024\/01\/prj-en_saugella-00-cover-all-B.jpg","width":2000,"height":1125},{"@type":"BreadcrumbList","@id":"https:\/\/maked.it\/en\/portfolio\/empowerment-in-a-label\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/maked.it\/en\/"},{"@type":"ListItem","position":2,"name":"Empowerment in a label"}]},{"@type":"WebSite","@id":"https:\/\/maked.it\/en\/#website","url":"https:\/\/maked.it\/en\/","name":"Maked","description":"We make design and digital communication","publisher":{"@id":"https:\/\/maked.it\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/maked.it\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/maked.it\/en\/#organization","name":"Graphic Store s.r.l.","url":"https:\/\/maked.it\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/maked.it\/en\/#\/schema\/logo\/image\/","url":"https:\/\/maked.it\/wp-content\/uploads\/2023\/12\/logo-maked.png","contentUrl":"https:\/\/maked.it\/wp-content\/uploads\/2023\/12\/logo-maked.png","width":340,"height":88,"caption":"Graphic Store s.r.l."},"image":{"@id":"https:\/\/maked.it\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/makedagency\/","https:\/\/www.instagram.com\/makedagency\/","https:\/\/it.linkedin.com\/company\/maked"]}]}},"_links":{"self":[{"href":"https:\/\/maked.it\/en\/wp-json\/wp\/v2\/portfolio\/3801","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/maked.it\/en\/wp-json\/wp\/v2\/portfolio"}],"about":[{"href":"https:\/\/maked.it\/en\/wp-json\/wp\/v2\/types\/portfolio"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/maked.it\/en\/wp-json\/wp\/v2\/media\/3802"}],"wp:attachment":[{"href":"https:\/\/maked.it\/en\/wp-json\/wp\/v2\/media?parent=3801"}],"wp:term":[{"taxonomy":"brand","embeddable":true,"href":"https:\/\/maked.it\/en\/wp-json\/wp\/v2\/brand?post=3801"},{"taxonomy":"homepage","embeddable":true,"href":"https:\/\/maked.it\/en\/wp-json\/wp\/v2\/homepage?post=3801"},{"taxonomy":"servizio","embeddable":true,"href":"https:\/\/maked.it\/en\/wp-json\/wp\/v2\/servizio?post=3801"},{"taxonomy":"settore","embeddable":true,"href":"https:\/\/maked.it\/en\/wp-json\/wp\/v2\/settore?post=3801"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}